{"id":72,"date":"2019-08-11T22:23:39","date_gmt":"2019-08-11T22:23:39","guid":{"rendered":"http:\/\/seishinaikidomallorca.com\/?page_id=72"},"modified":"2024-12-05T12:27:38","modified_gmt":"2024-12-05T10:27:38","slug":"aikido","status":"publish","type":"page","link":"https:\/\/seishinaikidomallorca.com\/en\/aikido","title":{"rendered":"Aikido"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"72\" class=\"elementor elementor-72\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5fc6f26 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5fc6f26\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d02b224\" data-id=\"d02b224\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1028973 elementor-widget elementor-widget-image\" data-id=\"1028973\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"230\" src=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/Seiza-e1513560102942.jpg\" class=\"attachment-large size-large wp-image-172\" alt=\"\" srcset=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/Seiza-e1513560102942.jpg.webp 800w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/Seiza-e1513560102942-300x86.jpg.webp 300w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/Seiza-e1513560102942-768x221.jpg.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7641627 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7641627\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44b34f1\" data-id=\"44b34f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-91cf64c elementor-widget elementor-widget-heading\" data-id=\"91cf64c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><h2 data-elementor-setting-key=\"title\" data-pen-placeholder=\"Teclea aqu\u00ed...\" style=\"font-family: var( --e-global-typography-primary-font-family ), Sans-serif;font-weight: var( --e-global-typography-primary-font-weight )\">AIKIDO EN MALLORCA. PALMA Y SINEU.<\/h2><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-efaf9b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"efaf9b2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-67a7f7a\" data-id=\"67a7f7a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5cfec5 elementor-widget elementor-widget-heading\" data-id=\"a5cfec5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfPor qu\u00e9 un arte marcial? \n\u00bfPor qu\u00e9 Aikido?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-453d5958 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"453d5958\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4bcf7d88\" data-id=\"4bcf7d88\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e96e6ae elementor-widget elementor-widget-text-editor\" data-id=\"5e96e6ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<p><span style=\"font-weight: 400;\">Educaci\u00f3n, Salud, Fortaleza, Flexibilidad, Autosuperaci\u00f3n, Disciplina, Autoconfianza, Respeto y Conocimiento. Estas son algunas de las bondades que aportan las artes marciales o budo modernos y por las cuales fueron creados.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El que se conoce a s\u00ed mismo, se fortalece y se domina, respeta a los dem\u00e1s y los protege. El que tiene miedo y se siente inferior, ataca e intenta da\u00f1ar a otros.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aikido es un Budo, traducido a menudo como arte marcial moderno, de origen japon\u00e9s, al igual que el Karate-do, Judo, Kendo, Iaido, etc. Aikido se caracteriza por sus t\u00e9cnicas de car\u00e1cter principalmente defensivo, por no incluir competici\u00f3n(exceptuando algunas l\u00edneas como el Aikido Tomiki) y por una base filos\u00f3fica muy potente orientada a la paz, tanto interna como en la relaci\u00f3n con otros.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aplicado en la vida diaria, son muchos los beneficios que ofrece el Aikido, arte marcial que permite estar en armon\u00eda con uno mismo y con quien nos rodea.<\/span><\/p>\n<p><span style=\"font-family: 'book antiqua', palatino, serif;\"><em><i><span style=\"font-weight: 400;\">\u201cComo Ai (armon\u00eda) es igual a Ai (amor), he decidido llamar \u201cAikido\u201d a mi \u00fanico Budo. Si bien la expresi\u00f3n \u201cAiki\u201d es antigua, el uso que los guerreros daban en el pasado a este t\u00e9rmino es diferente al m\u00edo. Aiki no es una t\u00e9cnica para luchar con el enemigo o para derrotarle, sino una v\u00eda para reconciliar al mundo y hacer de los seres humanos una familia.\u201d<\/span><\/i><\/em><\/span><\/p>\n<p style=\"text-align: right;\"><strong><span style=\"font-size: 10pt;\">Budo Renshu, O\u2019Sensei, Morihei Ueshiba<\/span><\/strong><\/p>\n<p>\u00a0<\/p>\n<p><em><span style=\"font-family: 'book antiqua', palatino, serif;\"><i><span style=\"font-weight: 400;\">\u201cHerir a un oponente es herirte a ti mismo.\u00a0 Controlar la agresi\u00f3n sin infligir da\u00f1o es el Arte de la Paz.\u201d<\/span><\/i><\/span><\/em><\/p>\n<p style=\"text-align: right;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 10pt;\"><strong>El Arte de la Paz, O\u2019Sensei, Morihei Ueshiba<\/strong><\/span><\/p>\n<div>\u00a0<\/div>\n<p><span style=\"font-weight: 400;\">A partir de las artes marciales japonesas utilizadas por los samurai, nace el Aikido, que es\u00a0 desarrollado por el maestro Morihei Ueshiba a principios del siglo XX, al que llamamos tambi\u00e9n O\u2019Sensei (Gran Maestro). A diferencia del Jiu-jitsu y de los Koryu antiguos, de los cuales deriva, Aikido es un Budo o arte marcial moderno orientado al desarrollo integral a trav\u00e9s del estudio del conflicto y su soluci\u00f3n no agresiva. Por tanto no es el objetivo del Aikido derrotar a un oponente en combate, si no reconducir el conflicto aprovechando la energ\u00eda del ataque del otro a un punto neutral en el cual nadie resulte herido. As\u00ed pues, el Aikido que es conocido como el \u201cArte de la Paz\u201d, hace referencia a un estado de calma propio de su practicante, quien ser\u00e1 el llamado a buscar la mejor soluci\u00f3n para ambas partes, tanto en un conflicto f\u00edsico como en el plano psicol\u00f3gico o emocional.<\/span><\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1016d66 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1016d66\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fa836db\" data-id=\"fa836db\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea7835f elementor-widget elementor-widget-heading\" data-id=\"ea7835f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La pr\u00e1ctica del Aikido<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-745dcd4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"745dcd4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a13004b\" data-id=\"a13004b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db77d8e elementor-widget elementor-widget-image\" data-id=\"db77d8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/morihei-ueshiba-hiroshi-tada-750px.jpg\" title=\"morihei-ueshiba-hiroshi-tada-750px\" alt=\"morihei-ueshiba-hiroshi-tada-750px\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7bb270f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7bb270f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9da505a\" data-id=\"9da505a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4cbaf42 elementor-widget elementor-widget-text-editor\" data-id=\"4cbaf42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em><span style=\"font-family: 'book antiqua', palatino, serif;\"><i><span style=\"font-weight: 400;\">\u201cEl hierro est\u00e1 lleno de impurezas que lo debilitan, a trav\u00e9s de su forja, se convierte en acero y es transformado en una espada bien afilada.\u00a0 Los seres humanos se desarrollan de la misma forma.\u201d<\/span><\/i><\/span><\/em><\/p>\n<p style=\"text-align: right;\"><span style=\"font-size: 10pt;\"><strong><span style=\"font-family: arial, helvetica, sans-serif;\">El Arte de la Paz, O\u2019Sensei, Morihei Ueshiba<\/span><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">La pr\u00e1ctica del Aikido se realiza en un Dojo. El Dojo suele disponer de un suelo especial llamado tatami que permite la pr\u00e1ctica de ca\u00eddas de forma segura, evitando lesiones. En los Budo, el Dojo es un lugar muy respetado y tanto el sensei (maestro) como los alumnos tienen el deber de cuidarlo y mantenerlo en buenas condiciones para la pr\u00e1ctica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Una clase de Aikido consiste en un calentamiento espec\u00edfico que da paso a la pr\u00e1ctica y repetici\u00f3n de las distintas t\u00e9cnicas propuestas por el sensei. Habitualmente se trabaja en parejas que intercambian los papeles de tori y uke respectivamente (defensor y atacante). A trav\u00e9s de la repetici\u00f3n se va puliendo al practicante, tanto a nivel f\u00edsico como mental y espiritual, logrando una optimizaci\u00f3n del uso del cuerpo, un estado de calma durante el conflicto y una conexi\u00f3n armonizada con el movimiento que est\u00e1n generando tanto uke como tori.<\/span><\/p>\n<p><em><span style=\"font-family: 'book antiqua', palatino, serif;\"><i><span style=\"font-weight: 400;\">\u201cAikido es trabajo duro.\u201d<\/span><\/i><\/span><\/em><\/p>\n<p style=\"text-align: right;\"><strong><span style=\"font-family: arial, helvetica, sans-serif; font-size: 10pt;\">Yamaguchi Seigo Sensei.<\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a4072e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4072e0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dc7ac8f\" data-id=\"dc7ac8f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-212ba5c elementor-widget elementor-widget-image\" data-id=\"212ba5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/yamaguchi-1024x576.jpg\" class=\"attachment-large size-large wp-image-176\" alt=\"\" srcset=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/yamaguchi-1024x576.jpg.webp 1024w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/yamaguchi-300x169.jpg.webp 300w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/yamaguchi-768x432.jpg.webp 768w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/yamaguchi.jpg.webp 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5da3774 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5da3774\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6a087ef\" data-id=\"6a087ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa76deb elementor-widget elementor-widget-text-editor\" data-id=\"aa76deb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Aikido, al incluir proyecciones y ca\u00eddas nage waza, t\u00e9cnicas de control gatame waza y atemis (tanto para el atacante como el defensor), resulta en un trabajo f\u00edsico completo tanto a nivel de coordinaci\u00f3n como de flexibilidad articular. Adem\u00e1s, Aikido requiere del practicante que mantenga una actitud relajada, imprescindible para la correcta ejecuci\u00f3n de las t\u00e9cnicas. Tambi\u00e9n incluye trabajo con armas, bokken, tanto y jo. Esta amplitud de facetas, incluyendo trabajos aer\u00f3bicos, de flexibilidad, relajaci\u00f3n y tambi\u00e9n de fuerza, resultan en una pr\u00e1ctica integral a nivel f\u00edsico. Es importante recalcar el esp\u00edritu de superaci\u00f3n y esfuerzo necesario que se logra a trav\u00e9s de la disciplina y la continuidad en la pr\u00e1ctica como herramienta fundamental para el progreso en el Aikido, arte marcial que los requiere de forma m\u00e1s rigurosa que en cualquier otra. Gracias a ello se forma tambi\u00e9n el esp\u00edritu de superaci\u00f3n del practicante, sin duda uno de los objetivos m\u00e1s preciados para la \u00e9poca en la que vivimos.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ce1de7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ce1de7c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b7651b\" data-id=\"5b7651b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a82b184 elementor-widget elementor-widget-image\" data-id=\"a82b184\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"547\" height=\"290\" src=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/endoseminar2.jpg\" class=\"attachment-large size-large wp-image-154\" alt=\"\" srcset=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/endoseminar2.jpg.webp 547w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/endoseminar2-300x159.jpg.webp 300w\" sizes=\"(max-width: 547px) 100vw, 547px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d785f76 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d785f76\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-09546f9\" data-id=\"09546f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfaa362 elementor-widget elementor-widget-text-editor\" data-id=\"cfaa362\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">La palabra Aikido est\u00e1 formada por tres ideogramas, Ai (armon\u00eda), Ki (energ\u00eda), Do (camino). Esto es as\u00ed porque en Aikido se busca conectar y unificar las energ\u00edas de atacante y defensor o uke y tori. Este concepto es la base del aiki o ki musubi. El objetivo de la t\u00e9cnica de Aikido es alcanzar esta forma de trabajo en la cual tori no choca con uke si no que ambos se mueven juntos, y donde uke aporta la energ\u00eda con su ataque mientras tori aplica solo la energ\u00eda m\u00ednima para guiar ese ataque.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bc1c7ab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc1c7ab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4bb0702\" data-id=\"4bb0702\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe3a07d elementor-widget elementor-widget-text-editor\" data-id=\"fe3a07d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em><span style=\"font-family: 'book antiqua', palatino, serif;\"><i><span style=\"font-weight: 400;\">\u201cEn el Arte de la Paz nunca atacamos.\u00a0 Un ataque es la prueba de que uno est\u00e1 fuera de control.\u00a0 Nunca escapes de cualquier tipo de reto, pero no trates de suprimir o controlar a un enemigo forzosamente.\u00a0 Deja que los atacantes vengan de la forma que quieran y entonces amoldate con ellos.\u00a0 Nunca persigas a los oponentes, redirige cada ataque y mant\u00e9nte firme detr\u00e1s de \u00e9l.\u201d<\/span><\/i><\/span><\/em><\/p>\n<p style=\"text-align: right;\"><strong><span style=\"font-size: 10pt; font-family: arial, helvetica, sans-serif;\">O\u2019Sensei, Morihei Ueshiba<\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a8bc2c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a8bc2c9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c5fdbb4\" data-id=\"c5fdbb4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-628ae27 elementor-widget elementor-widget-heading\" data-id=\"628ae27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La filosof\u00eda del Aikido<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fca14f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fca14f7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7100c7d\" data-id=\"7100c7d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-feab68f elementor-widget elementor-widget-image\" data-id=\"feab68f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"270\" height=\"186\" src=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/images.jpg\" class=\"attachment-large size-large wp-image-158\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4565132 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4565132\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e653c9f\" data-id=\"e653c9f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ffe7b5 elementor-widget elementor-widget-text-editor\" data-id=\"2ffe7b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em><span style=\"font-family: 'book antiqua', palatino, serif;\"><i><span style=\"font-weight: 400;\">\u201cEl arte de la Paz comienza contigo. Trabaja en ti mismo y en tu tarea destinada en el Arte de la Paz. Todo el mundo tiene un esp\u00edritu que puede ser refinado, un cuerpo que puede ser entrenado de cierta manera, un camino adecuado el cual seguir.\u00a0 T\u00fa est\u00e1s aqu\u00ed sin m\u00e1s prop\u00f3sito que comprender tu divinidad interna y manifestar iluminaci\u00f3n innata.\u00a0 Crear paz en tu propia vida y luego aplicar el Arte a todo el que te encuentres.\u201c<\/span><\/i><\/span><\/em><\/p>\n<p style=\"text-align: right;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong><span style=\"font-size: 10pt;\">El Arte de la Paz. O\u2019Sensei, Morihei Ueshiba.<\/span><\/strong><\/span><\/p>\n<p><em><span style=\"font-family: 'book antiqua', palatino, serif;\"><i><span style=\"font-weight: 400;\">\u201cSi cambias de postura, cambiar\u00e1s de actitud. Si cambias de actitud, algo en tu interior va a cambiar. Si algo en tu interior cambia, toda tu vida va a cambiar. Si tu vida cambia, todo tu destino va a cambiar.\u201c<\/span><\/i><\/span><\/em><\/p>\n<p style=\"text-align: right;\"><strong><span style=\"font-size: 10pt; font-family: arial, helvetica, sans-serif;\">Hikitsuchi Michio Sensei.<\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c57e990 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c57e990\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-862a006\" data-id=\"862a006\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f8e5f77 elementor-widget elementor-widget-image\" data-id=\"f8e5f77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"292\" height=\"300\" src=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/morehei_ueshiba_hikitsuchi_sensei_aikido-292x300.png\" class=\"attachment-medium size-medium wp-image-164\" alt=\"\" srcset=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/morehei_ueshiba_hikitsuchi_sensei_aikido-292x300.png.webp 292w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/morehei_ueshiba_hikitsuchi_sensei_aikido-768x789.png.webp 768w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/morehei_ueshiba_hikitsuchi_sensei_aikido.png.webp 793w\" sizes=\"(max-width: 292px) 100vw, 292px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d55d58c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d55d58c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-146efab\" data-id=\"146efab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-719d3e7 elementor-widget elementor-widget-text-editor\" data-id=\"719d3e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">El Aikido es entre otras cosas, el estudio del conflicto y de c\u00f3mo nos desenvolvemos dentro de \u00e9ste. El conflicto es parte de la vida y nos va a acompa\u00f1ar a todos los niveles. El Aikido propone armonizarse con el conflicto, frente a las dos tendencias o instintos b\u00e1sicos que solemos utilizar como son la lucha o la huida. En lugar de huir o chocar, Aikido propone fluir con la energ\u00eda del ataque y equilibrar dicha energ\u00eda. Esto, que no parece sencillo a simple vista, efectivamente resulta complejo de llevar a cabo en la realidad de un encuentro f\u00edsico o psicol\u00f3gico. Curiosamente, resulta complejo en parte por todo lo que debemos aprender como: t\u00e9cnica, repetici\u00f3n, perfeccionamiento, interiorizaci\u00f3n\u2026 pero sobre todo por lo que debemos de abandonar: ego, intenci\u00f3n de dominar o ganar, etc\u2026 que implican un trabajo interno muy potente para llenar lo vac\u00edo y vaciar lo lleno. El Aikido, arte marcial que presenta el conflicto como la otra cara de la calma, no juzga la violencia por s\u00ed misma sino que busca encontrar la armon\u00eda y el equilibrio cuando el conflicto se presenta.<\/span><\/p>\n<p><em><span style=\"font-family: 'book antiqua', palatino, serif;\"><span style=\"font-weight: 400;\">\u201cMasakatsu Agatsu Katsuhayabi: <\/span><i><span style=\"font-weight: 400;\">la verdadera victoria es la victoria sobre uno mismo. Que ese d\u00eda llegue pronto!\u201d<\/span><\/i><\/span><\/em><\/p>\n<p style=\"text-align: right;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 10pt;\"><span style=\"font-weight: bold;\">O\u2019Sensei Morihei Ueshiba<\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78bb362 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78bb362\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d2b934a\" data-id=\"d2b934a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1394886 elementor-widget elementor-widget-image\" data-id=\"1394886\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"493\" src=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/3632349225_98666d7e17.jpg\" class=\"attachment-large size-large wp-image-148\" alt=\"\" srcset=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/3632349225_98666d7e17.jpg 500w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/3632349225_98666d7e17-300x296.jpg.webp 300w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/3632349225_98666d7e17-100x100.jpg 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9220ab8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9220ab8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a950f2\" data-id=\"2a950f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a22e8e1 elementor-widget elementor-widget-spacer\" data-id=\"a22e8e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c6e03b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c6e03b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-967a5af\" data-id=\"967a5af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d342f1 elementor-widget elementor-widget-heading\" data-id=\"1d342f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">O\u2019Sensei Morihei Ueshiba<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db0e8fb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db0e8fb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e4a121\" data-id=\"7e4a121\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-797be84 elementor-widget elementor-widget-image\" data-id=\"797be84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"760\" height=\"1024\" src=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/osensei7-760x1024.jpg\" class=\"attachment-large size-large wp-image-169\" alt=\"\" srcset=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/osensei7.jpg.webp 760w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/osensei7-223x300.jpg.webp 223w\" sizes=\"(max-width: 760px) 100vw, 760px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-645049c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"645049c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9de8f4e\" data-id=\"9de8f4e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-97b790d elementor-widget elementor-widget-text-editor\" data-id=\"97b790d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">O\u2019Sensei (Gran Maestro) Morihei Ueshiba fue un artista marcial excepcional nacido el 14 de Diciembre de 1883 en Tanabe, prefectura de Wakayama que domin\u00f3 diversas artes marciales como daito ryu jiujitsu y escuelas de armas as\u00ed como tambi\u00e9n, distintas escuelas de budismo Shingon y shintoistas como la Omoto kyo. A partir de todas estas experiencias desarroll\u00f3 un estilo marcial denominado en un principio Aikijutsu que fue posteriormente conocido como Aikido.<\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-weight: 400;\">Seg\u00fan sus alumnos, Morihei Ueshiba ten\u00eda un car\u00e1cter fuerte pero a su vez pod\u00eda ser c\u00e1lido como un abuelo con sus nietos. Vivi\u00f3 y luch\u00f3 en la segunda guerra mundial, al frente de las tropas japonesas y fue referente de las artes guerreras de la \u00e9poca, entre otros muchos acontecimientos vitales. Tras observar la destrucci\u00f3n a la que se hab\u00eda llegado, decidi\u00f3 buscar un sentido a las artes marciales, es por eso que a partir de su estudio y determinaci\u00f3n, naci\u00f3 el Aikido que conocemos actualmente y que tiene el prop\u00f3sito de unir y construir en lugar de destruir y separar. He aqu\u00ed la grandeza de este genio que supo ver en el Budo su potencial creativo.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0406e17 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0406e17\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8dae7cc\" data-id=\"8dae7cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8c289c elementor-widget elementor-widget-image\" data-id=\"a8c289c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"779\" height=\"1024\" src=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/osensei4-779x1024.jpg\" class=\"attachment-large size-large wp-image-168\" alt=\"\" srcset=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/osensei4-779x1024.jpg.webp 779w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/osensei4-228x300.jpg.webp 228w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/osensei4-768x1009.jpg.webp 768w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/osensei4.jpg.webp 800w\" sizes=\"(max-width: 779px) 100vw, 779px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-07c6ac3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"07c6ac3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d40ed1b\" data-id=\"d40ed1b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1644bd9 elementor-widget elementor-widget-text-editor\" data-id=\"1644bd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><i><span style=\"font-weight: 400;\">\u201cSi tu coraz\u00f3n es tan grande como para envolver a tus adversarios, t\u00fa puedes ver a trav\u00e9s de ellos y evadir sus ataques.\u00a0 Y una vez que los envuelvas, t\u00fa podr\u00e1s ser capaz de guiarlos a trav\u00e9s de una v\u00eda indicada por ti, el cielo y la tierra.\u201d<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">O\u2019Sensei Morihei Ueshiba muri\u00f3 el 26 de Abril de 1969, practicando Aikido y sorprendiendo por su energ\u00eda y vitalidad hasta casi el final de sus d\u00edas. Es recordado cada d\u00eda en todas las clases y en cada rinc\u00f3n del mundo donde se practica Aikido.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-50e562c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"50e562c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aa4f4c8\" data-id=\"aa4f4c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-998486c elementor-widget elementor-widget-spacer\" data-id=\"998486c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a2861d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a2861d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eb7938b\" data-id=\"eb7938b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2745707 elementor-widget elementor-widget-heading\" data-id=\"2745707\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Seishiro Endo Shihan<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fd407fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd407fd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ffd91f0\" data-id=\"ffd91f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b04101 elementor-widget elementor-widget-text-editor\" data-id=\"0b04101\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Seishiro Endo Shihan naci\u00f3 en 1942 en Saku, Nagano, Jap\u00f3n. Es 8\u00ba Dan de Aikido y es uno de los pocos alumnos vivos que estudiaron bajo el fundador de Aikido Morihei Ueshiba. Alumno tambi\u00e9n de los maestros de Hombu Dojo Yamaguchi Sensei, Tada Sensei, Kanai Sensei y Kobayashi Sensei, entre otros, sufre un accidente en su hombro derecho a los 30 a\u00f1os de edad que le obliga a cambiar su forma de practicar Aikido, volvi\u00e9ndose mucho m\u00e1s suave y desarrollando un Aikido de contacto.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ac1f19 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ac1f19\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fe8b9a0\" data-id=\"fe8b9a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7895b7 elementor-widget elementor-widget-image\" data-id=\"a7895b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/YDoMPgXh_400x400.jpg\" class=\"attachment-large size-large wp-image-146\" alt=\"\" srcset=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/YDoMPgXh_400x400.jpg.webp 400w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/YDoMPgXh_400x400-150x150.jpg.webp 150w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/YDoMPgXh_400x400-300x300.jpg.webp 300w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/YDoMPgXh_400x400-100x100.jpg 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d213e2a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d213e2a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc8fe5a\" data-id=\"fc8fe5a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6cda8d elementor-widget elementor-widget-text-editor\" data-id=\"c6cda8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em><span style=\"font-family: 'book antiqua', palatino, serif;\"><i><span style=\"font-weight: 400;\">\u201cEmpec\u00e9 a revisar constantemente mi estado interno, tanto si todo iba bien como si iba mal, cuando intentaba derrotar a mi compa\u00f1ero, cuando sent\u00eda miedo, inseguridad, etc. De esas sensaciones aprend\u00ed la importancia de mantener siempre una calma mental.\u201d<\/span><\/i><\/span><\/em><\/p>\n<p style=\"text-align: right;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 10pt;\"><strong>Endo Seishiro Shihan<\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51a41be elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"51a41be\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f47cdb9\" data-id=\"f47cdb9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27041f3 elementor-widget elementor-widget-text-editor\" data-id=\"27041f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">El Aikido del maestro Endo Sensei se caracteriza por la suavidad en su ejecuci\u00f3n, el contacto entre tori y uke y tambi\u00e9n por la importancia en la distancia e intenci\u00f3n tanto por parte de tori como de uke. Esta forma de pr\u00e1ctica requiere un constante chequeo interno y adaptaci\u00f3n a lo que est\u00e1 ocurriendo a cada instante, desarrollando la intuici\u00f3n y la adaptabilidad de los practicantes.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f4ae4d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f4ae4d4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f87404\" data-id=\"6f87404\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4412fa7 elementor-widget elementor-widget-image\" data-id=\"4412fa7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"484\" src=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/la-foto-787437.jpg\" class=\"attachment-large size-large wp-image-161\" alt=\"\" srcset=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/la-foto-787437.jpg.webp 720w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/la-foto-787437-300x202.jpg.webp 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad713ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad713ef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad7f786\" data-id=\"ad7f786\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7eebfd elementor-widget elementor-widget-text-editor\" data-id=\"f7eebfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">La forma de trabajo del Sensei Endo Seishiro es conocida como la EndoWay: el camino o la forma de Endo. Miles de practicantes de todo el mundo estudian bajo su direcci\u00f3n y cuenta con deshis o alumnos directos como Kaname Ariga Sensei en Jap\u00f3n o Lu\u00eds Moch\u00f3n Sensei en Espa\u00f1a.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6527ea7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6527ea7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e0e499\" data-id=\"6e0e499\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d99866 elementor-widget elementor-widget-spacer\" data-id=\"3d99866\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-07fdbc7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"07fdbc7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-091f34b\" data-id=\"091f34b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-093e880 elementor-widget elementor-widget-heading\" data-id=\"093e880\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lu\u00eds F. Moch\u00f3n Corredor Sensei<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-82579a7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"82579a7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8aaa71b\" data-id=\"8aaa71b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d25931b elementor-widget elementor-widget-text-editor\" data-id=\"d25931b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Lu\u00eds Francisco Moch\u00f3n Corredor (Granada, 1975) es un maestro de Aikido, 5\u00ba Dan, y Shidoin(maestro) por el Aikikai Hombu Dojo de Tokyo, alumno de Endo Seishiro Shihan, 8\u00ba Dan de Aikido. Lu\u00eds Moch\u00f3n Sensei es un maestro de reconocimiento internacional que realiza seminarios en toda la geograf\u00eda espa\u00f1ola y tambi\u00e9n en el extranjero(Italia, Malta, Argentina, Chile, Israel). Representante de la Endo Way, como se conoce a la l\u00ednea de pr\u00e1ctica del maestro Endo Seishiro, Lu\u00eds Moch\u00f3n sensei cuenta con cientos de alumnos repartidos por todo el mundo.<\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-weight: 400;\">Lu\u00eds Moch\u00f3n sensei imparte clases regularmente en el Dojo Musubi de Granada. Debido a que varios de sus alumnos son tambi\u00e9n sensei de Aikido repartidos por toda Espa\u00f1a, se conoce a su grupo de Dojos como Musubi No Kokoro (Coraz\u00f3n o esp\u00edritu Musubi).<\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-weight: 400;\">Lu\u00eds Moch\u00f3n es uno de los pocos deshi (alumnos de confianza) de Endo sensei. A pesar de que Endo sensei cuenta con miles de alumnos alrededor del mundo, s\u00f3lo aquellos que deciden dedicar su vida al Aikido y aceptan su grado de compromiso, pueden optar a ser deshi del maestro. Al igual que el maestro Endo; uno de los pocos maestros vivos de las primeras generaciones del Aikido, la pr\u00e1ctica de Lu\u00eds Moch\u00f3n Sensei se caracteriza por un estudio y una b\u00fasqueda profunda dentro de este arte marcial.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a68951 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a68951\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a18ae66\" data-id=\"a18ae66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d4b136 elementor-widget elementor-widget-image\" data-id=\"0d4b136\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"917\" src=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-05-22-at-11.50.58-768x917.jpeg\" class=\"attachment-medium_large size-medium_large wp-image-298\" alt=\"\" srcset=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-05-22-at-11.50.58-768x917.jpeg.webp 768w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-05-22-at-11.50.58-251x300.jpeg.webp 251w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-05-22-at-11.50.58-857x1024.jpeg.webp 857w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-05-22-at-11.50.58.jpeg 1080w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9dd8aa7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9dd8aa7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c177a38\" data-id=\"c177a38\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a4101a elementor-widget elementor-widget-spacer\" data-id=\"8a4101a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-60f0678 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60f0678\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d5b6f55\" data-id=\"d5b6f55\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a635266 elementor-widget elementor-widget-heading\" data-id=\"a635266\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Aikikai, Hombu Dojo y Federaci\u00f3n Internacional de Aikido IAF<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4cd917c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4cd917c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-91452de\" data-id=\"91452de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bc8f30 elementor-widget elementor-widget-text-editor\" data-id=\"5bc8f30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Aikikai es una organizaci\u00f3n mundial fundada por el hijo del fundador, Morihei Ueshiba, Kisshomaru Ueshiba para continuar con el trabajo creado por su padre. No todas las l\u00edneas de Aikido est\u00e1n bajo la supervisi\u00f3n de la Aikikai, pero si la gran mayor\u00eda. La Aikikai establece una unificaci\u00f3n de criterios para la organizaci\u00f3n del Aikido a nivel internacional, como pueden ser los grados o las titulaciones de ense\u00f1anza.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Hombu Dojo es el Dojo central de la Aikikai, situado en Tokyo, donde reside tambi\u00e9n el actual Doshu o director de la Aikikai, Moriteru Ueshiba, nieto del fundador. En Hombu Dojo imparten clases diversos Shihan o maestros de maestros de la Aikikai.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fbcc6b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fbcc6b2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dca1989\" data-id=\"dca1989\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f769e3d elementor-widget elementor-widget-image\" data-id=\"f769e3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"587\" src=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/aikikai-hombu-dojo-2-2-1024x587.jpg\" class=\"attachment-large size-large wp-image-149\" alt=\"\" srcset=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/aikikai-hombu-dojo-2-2-1024x587.jpg 1024w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/aikikai-hombu-dojo-2-2-300x172.jpg.webp 300w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/aikikai-hombu-dojo-2-2-768x440.jpg.webp 768w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/aikikai-hombu-dojo-2-2.jpg.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bac3a25 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bac3a25\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-df27c56\" data-id=\"df27c56\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73b4b09 elementor-widget elementor-widget-text-editor\" data-id=\"73b4b09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">La Federaci\u00f3n Internacional de Aikido, IAF, es un organismo dependiente de la Aikikai que se encarga de contactar y servir de puente entre la Aikikai y los distintos organismos gubernamentales y deportivos internacionales para coordinar todos los eventos relacionados con el Aikido seg\u00fan las directrices de la Aikikai.<\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-weight: 400;\">La IAF o Federaci\u00f3n Internacional de Aikido, junto con la Aikikai, son las encargadas de reconocer a las organizaciones de los distintos pa\u00edses que representan al Aikido para garantizar de esta forma la uniformidad a nivel de graduaciones y titulaciones.<\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-weight: 400;\">Actualmente existen varias organizaciones en Espa\u00f1a reconocidas por el Aikikai y la IAF como representantes del Aikikai en Espa\u00f1a, entre las que se encuentran Spain Aikikai, ACAE o Aetaiki, entre otras. La mayor\u00eda de ellas est\u00e1n unificadas bajo la Federaci\u00f3n Nacional de Aikido Aikikai de Espa\u00f1a, creada a petici\u00f3n de la Federaci\u00f3n Internacional de Aikido como estructura en nuestro pa\u00eds para la organizaci\u00f3n del Aikido y la comunicaci\u00f3n con \u00e9sta.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5dad9d3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5dad9d3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ba8bad3\" data-id=\"ba8bad3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b864d9 elementor-widget elementor-widget-image\" data-id=\"0b864d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/AIKIKAI-logo-07CBA50695-seeklogo_com.gif\" class=\"attachment-large size-large wp-image-150\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddda40c elementor-widget elementor-widget-image\" data-id=\"ddda40c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/logo-nuevo-iaf-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-162\" alt=\"\" srcset=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/logo-nuevo-iaf-150x150.png.webp 150w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/logo-nuevo-iaf-300x300.png.webp 300w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/logo-nuevo-iaf-768x768.png.webp 768w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/logo-nuevo-iaf-100x100.png.webp 100w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/logo-nuevo-iaf.png.webp 960w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f83fd8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f83fd8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-32fcb18\" data-id=\"32fcb18\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e07b28b elementor-widget elementor-widget-image\" data-id=\"e07b28b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"130\" height=\"130\" src=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2021\/07\/FNAAE-Colour-Logo-130x130.jpg\" class=\"attachment-medium size-medium wp-image-299\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f0a7ad7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f0a7ad7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c33f767\" data-id=\"c33f767\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7f8695 elementor-widget elementor-widget-spacer\" data-id=\"a7f8695\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39c3c4b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39c3c4b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a9d357d\" data-id=\"a9d357d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d98f3ec elementor-widget elementor-widget-heading\" data-id=\"d98f3ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Spain Aikikai<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65aece0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"65aece0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f224aa2\" data-id=\"f224aa2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ccd6b8b elementor-widget elementor-widget-text-editor\" data-id=\"ccd6b8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Spain Aikikai es la Asociaci\u00f3n Nacional de Dojos de Aikido Aikikai de Espa\u00f1a, es una organizaci\u00f3n centrada en permitir que cualquier practicante de Aikido, o mejor dicho, Dojo de Aikido, pueda estar bajo una estructura federativa bajo la supervisi\u00f3n directa de la Aikikai de Jap\u00f3n, y como consecuencia, de todos sus practicantes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Este era un vac\u00edo que exist\u00eda a nivel nacional hasta la aparici\u00f3n de la Spain Aikikai y otras organizaciones nombradas anteriormente. Hasta entonces, en Espa\u00f1a no era posible obtener grados Aikikai o titulaciones de ense\u00f1anza oficiales de la Aikikai si no se segu\u00eda a determinado Shihan Aikikai de forma individual.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Actualmente Spain Aikikai organiza anualmente ex\u00e1menes de grado Aikikai para todos los socios aspirantes para obtener titulaciones oficiales emitidas directamente por el Aikikai de Jap\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En Seishin Aikido Mallorca somos miembros de la Spain Aikikai, siendo un Dojo oficial de la Aikikai de Jap\u00f3n en Espa\u00f1a y con profesores titulados para la docencia del Aikido, Arte Marcial regido seg\u00fan las directrices de la Aikikai y la Federaci\u00f3n Internacional de Aikido.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e6eb2c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e6eb2c4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0a16ca7\" data-id=\"0a16ca7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd82ded elementor-widget elementor-widget-video\" data-id=\"cd82ded\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=3AqTk3kDGW4&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>AIKIDO EN MALLORCA. PALMA Y SINEU. \u00bfPor qu\u00e9 un arte marcial? \u00bfPor qu\u00e9 Aikido? La pr\u00e1ctica del Aikido \u201cEl hierro est\u00e1 lleno de impurezas que lo debilitan, a trav\u00e9s de&hellip;&nbsp;<a href=\"https:\/\/seishinaikidomallorca.com\/en\/aikido\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Aikido<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","ngg_post_thumbnail":0,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-72","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aikido - SEISHIN AIKIDO MALLORCA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seishinaikidomallorca.com\/en\/aikido\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aikido - SEISHIN AIKIDO MALLORCA\" \/>\n<meta property=\"og:description\" content=\"AIKIDO EN MALLORCA. PALMA Y SINEU. \u00bfPor qu\u00e9 un arte marcial? \u00bfPor qu\u00e9 Aikido? La pr\u00e1ctica del Aikido \u201cEl hierro est\u00e1 lleno de impurezas que lo debilitan, a trav\u00e9s de&hellip;&nbsp;Read More &raquo;Aikido\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seishinaikidomallorca.com\/en\/aikido\/\" \/>\n<meta property=\"og:site_name\" content=\"SEISHIN AIKIDO MALLORCA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/seishinaikidomallorca\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-05T10:27:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/Seiza-e1513560102942.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/seishinaikidomallorca.com\/aikido\",\"url\":\"https:\/\/seishinaikidomallorca.com\/aikido\",\"name\":\"Aikido - SEISHIN AIKIDO MALLORCA\",\"isPartOf\":{\"@id\":\"https:\/\/seishinaikidomallorca.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/seishinaikidomallorca.com\/aikido#primaryimage\"},\"image\":{\"@id\":\"https:\/\/seishinaikidomallorca.com\/aikido#primaryimage\"},\"thumbnailUrl\":\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/Seiza-e1513560102942.jpg\",\"datePublished\":\"2019-08-11T22:23:39+00:00\",\"dateModified\":\"2024-12-05T10:27:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/seishinaikidomallorca.com\/aikido#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/seishinaikidomallorca.com\/aikido\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/seishinaikidomallorca.com\/aikido#primaryimage\",\"url\":\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/Seiza-e1513560102942.jpg\",\"contentUrl\":\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/Seiza-e1513560102942.jpg\",\"width\":800,\"height\":230},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/seishinaikidomallorca.com\/aikido#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/seishinaikidomallorca.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aikido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/seishinaikidomallorca.com\/#website\",\"url\":\"https:\/\/seishinaikidomallorca.com\/\",\"name\":\"SEISHIN AIKIDO MALLORCA\",\"description\":\"AIKIDO EN MALLORCA | AIKIDO EN PALMA Y SINEU\",\"publisher\":{\"@id\":\"https:\/\/seishinaikidomallorca.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/seishinaikidomallorca.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/seishinaikidomallorca.com\/#organization\",\"name\":\"SEISHIN AIKIDO MALLORCA\",\"url\":\"https:\/\/seishinaikidomallorca.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/seishinaikidomallorca.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/03\/mon-scaled.jpg\",\"contentUrl\":\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/03\/mon-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"SEISHIN AIKIDO MALLORCA\"},\"image\":{\"@id\":\"https:\/\/seishinaikidomallorca.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/seishinaikidomallorca\",\"https:\/\/www.instagram.com\/seishinaikidomallorca\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aikido - SEISHIN AIKIDO MALLORCA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seishinaikidomallorca.com\/en\/aikido\/","og_locale":"en_GB","og_type":"article","og_title":"Aikido - SEISHIN AIKIDO MALLORCA","og_description":"AIKIDO EN MALLORCA. PALMA Y SINEU. \u00bfPor qu\u00e9 un arte marcial? \u00bfPor qu\u00e9 Aikido? La pr\u00e1ctica del Aikido \u201cEl hierro est\u00e1 lleno de impurezas que lo debilitan, a trav\u00e9s de&hellip;&nbsp;Read More &raquo;Aikido","og_url":"https:\/\/seishinaikidomallorca.com\/en\/aikido\/","og_site_name":"SEISHIN AIKIDO MALLORCA","article_publisher":"https:\/\/www.facebook.com\/seishinaikidomallorca","article_modified_time":"2024-12-05T10:27:38+00:00","og_image":[{"url":"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/Seiza-e1513560102942.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seishinaikidomallorca.com\/aikido","url":"https:\/\/seishinaikidomallorca.com\/aikido","name":"Aikido - SEISHIN AIKIDO MALLORCA","isPartOf":{"@id":"https:\/\/seishinaikidomallorca.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seishinaikidomallorca.com\/aikido#primaryimage"},"image":{"@id":"https:\/\/seishinaikidomallorca.com\/aikido#primaryimage"},"thumbnailUrl":"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/Seiza-e1513560102942.jpg","datePublished":"2019-08-11T22:23:39+00:00","dateModified":"2024-12-05T10:27:38+00:00","breadcrumb":{"@id":"https:\/\/seishinaikidomallorca.com\/aikido#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seishinaikidomallorca.com\/aikido"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/seishinaikidomallorca.com\/aikido#primaryimage","url":"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/Seiza-e1513560102942.jpg","contentUrl":"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2019\/08\/Seiza-e1513560102942.jpg","width":800,"height":230},{"@type":"BreadcrumbList","@id":"https:\/\/seishinaikidomallorca.com\/aikido#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/seishinaikidomallorca.com\/"},{"@type":"ListItem","position":2,"name":"Aikido"}]},{"@type":"WebSite","@id":"https:\/\/seishinaikidomallorca.com\/#website","url":"https:\/\/seishinaikidomallorca.com\/","name":"SEISHIN AIKIDO MALLORCA","description":"AIKIDO EN MALLORCA | AIKIDO EN PALMA Y SINEU","publisher":{"@id":"https:\/\/seishinaikidomallorca.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seishinaikidomallorca.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/seishinaikidomallorca.com\/#organization","name":"SEISHIN AIKIDO MALLORCA","url":"https:\/\/seishinaikidomallorca.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/seishinaikidomallorca.com\/#\/schema\/logo\/image\/","url":"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/03\/mon-scaled.jpg","contentUrl":"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/03\/mon-scaled.jpg","width":2560,"height":2560,"caption":"SEISHIN AIKIDO MALLORCA"},"image":{"@id":"https:\/\/seishinaikidomallorca.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/seishinaikidomallorca","https:\/\/www.instagram.com\/seishinaikidomallorca"]}]}},"_links":{"self":[{"href":"https:\/\/seishinaikidomallorca.com\/en\/wp-json\/wp\/v2\/pages\/72","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seishinaikidomallorca.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/seishinaikidomallorca.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/seishinaikidomallorca.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/seishinaikidomallorca.com\/en\/wp-json\/wp\/v2\/comments?post=72"}],"version-history":[{"count":59,"href":"https:\/\/seishinaikidomallorca.com\/en\/wp-json\/wp\/v2\/pages\/72\/revisions"}],"predecessor-version":[{"id":1152,"href":"https:\/\/seishinaikidomallorca.com\/en\/wp-json\/wp\/v2\/pages\/72\/revisions\/1152"}],"wp:attachment":[{"href":"https:\/\/seishinaikidomallorca.com\/en\/wp-json\/wp\/v2\/media?parent=72"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}