{"id":1149,"date":"2024-12-05T12:25:01","date_gmt":"2024-12-05T10:25:01","guid":{"rendered":"https:\/\/seishinaikidomallorca.com\/?p=1149"},"modified":"2024-12-05T12:32:06","modified_gmt":"2024-12-05T10:32:06","slug":"aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca","status":"publish","type":"post","link":"https:\/\/seishinaikidomallorca.com\/en\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca","title":{"rendered":"Aikido. Guillermo Balderas Sensei. Enero 2025. Seishin Aikido Mallorca."},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/12\/467640769_1117305276881021_5944476159786189480_n-1024x1024.jpg\" alt=\"Aikido Mallorca. Guillermo Balderas Sensei.\" class=\"wp-image-1146\" srcset=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/12\/467640769_1117305276881021_5944476159786189480_n-1024x1024.jpg 1024w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/12\/467640769_1117305276881021_5944476159786189480_n-300x300.jpg 300w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/12\/467640769_1117305276881021_5944476159786189480_n-150x150.jpg 150w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/12\/467640769_1117305276881021_5944476159786189480_n-768x768.jpg 768w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/12\/467640769_1117305276881021_5944476159786189480_n-12x12.jpg 12w, https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/12\/467640769_1117305276881021_5944476159786189480_n.jpg 1440w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Seishin Aikido Mallorca. Guillermo Balderas Sensei.<\/figcaption><\/figure>\n\n\n\n<p>Seminario de Aikido en Mallorca. Guillermo Balderas Sensei. Seishin Dojo C\/Regal, 114. D\u00edas 10 y 11 de enero de 2025.<\/p>\n\n\n\n<p>Seminario de Aikido reconocido por Spain Aikikai y por la Federaci\u00f3n Nacional de Aikido Aikikai de Espa\u00f1a. Organiza Seishin Aikido Mallorca. Curso v\u00e1lido como requisito de ex\u00e1menes a cintur\u00f3n negro de Aikido por el Aikikai.<\/p>\n\n\n\n<p>Plazas limitadas. Imprescindible reserva previa.<\/p>\n\n\n\n<p><a href=\"https:\/\/l.facebook.com\/l.php?u=http%3A%2F%2Fwww.seishinaikidomallorca.com%2F%3Ffbclid%3DIwZXh0bgNhZW0CMTAAAR2iJOrLfLcdvc2vLhDmB5ycXPo5h_QAimUt_mzydkni7MH0Jf2TGkLCgBE_aem_ueqGZhUWUwaobzC1o9fuuA&amp;h=AT0awo0k9Ok3K-cx7LdkjRYBJpGARt8bGfese6_Hehf0DM9cuW9apX4yq9clMoIEwoAZ5LLMPVgcpk4B3BFBTebKniQfG8gfHfOqeomGX0c8ig6AdgugbOeh0s4rFMByW-Jg&amp;__tn__=-UK-R&amp;c[0]=AT1H4pjrdtVA4ojyA82LxF1GuDayXXMwcPa14n_2vGI6LuuDSAgLAUzuaRK9aTzXJsrmwpbhsYVV0ZwyDz3UMVY93Yp_MVNGQqrRqehs4OXdV-Fu61TMQtP28Dz_joKxiWcM3IFYnk8aOV997NE2cbHUSEY7CGZ2Nv_6JkIql56Ptu2tSYAOk5WC7Js3V1pd5VQsMQOFTzdnK0nIefpD3YYVRUM\" rel=\"noreferrer noopener\" target=\"_blank\">www.seishinaikidomallorca.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seminario de Aikido en Mallorca. Guillermo Balderas Sensei. Seishin Dojo C\/Regal, 114. D\u00edas 10 y 11 de enero de 2025. Seminario de Aikido reconocido por Spain Aikikai y por la&hellip;&nbsp;<a href=\"https:\/\/seishinaikidomallorca.com\/en\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Aikido. Guillermo Balderas Sensei. Enero 2025. Seishin Aikido Mallorca.<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":1146,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","ngg_post_thumbnail":0,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[5],"tags":[6,11,13,8,7,9,10,15,12,14,36,37],"class_list":["post-1149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aikido","tag-aikido","tag-aikido-en-inca","tag-aikido-en-mallorca","tag-aikido-inca","tag-aikido-mallorca","tag-aikido-palma","tag-aikido-sineu","tag-aikikai","tag-incaciutat","tag-mallorca","tag-mallorca-aikikai","tag-spain-aikikai"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aikido. Guillermo Balderas Sensei. Enero 2025. Seishin Aikido Mallorca. - SEISHIN AIKIDO MALLORCA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seishinaikidomallorca.com\/en\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aikido. Guillermo Balderas Sensei. Enero 2025. Seishin Aikido Mallorca. - SEISHIN AIKIDO MALLORCA\" \/>\n<meta property=\"og:description\" content=\"Seminario de Aikido en Mallorca. Guillermo Balderas Sensei. Seishin Dojo C\/Regal, 114. D\u00edas 10 y 11 de enero de 2025. Seminario de Aikido reconocido por Spain Aikikai y por la&hellip;&nbsp;Read More &raquo;Aikido. Guillermo Balderas Sensei. Enero 2025. Seishin Aikido Mallorca.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seishinaikidomallorca.com\/en\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca\/\" \/>\n<meta property=\"og:site_name\" content=\"SEISHIN AIKIDO MALLORCA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/seishinaikidomallorca\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-05T10:25:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-05T10:32:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/12\/467640769_1117305276881021_5944476159786189480_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"llorenc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"llorenc\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca#article\",\"isPartOf\":{\"@id\":\"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca\"},\"author\":{\"name\":\"llorenc\",\"@id\":\"https:\/\/seishinaikidomallorca.com\/#\/schema\/person\/b710dec9276d5d3ecacea9edc5d4cddc\"},\"headline\":\"Aikido. Guillermo Balderas Sensei. Enero 2025. Seishin Aikido Mallorca.\",\"datePublished\":\"2024-12-05T10:25:01+00:00\",\"dateModified\":\"2024-12-05T10:32:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca\"},\"wordCount\":80,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/seishinaikidomallorca.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca#primaryimage\"},\"thumbnailUrl\":\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/12\/467640769_1117305276881021_5944476159786189480_n.jpg\",\"keywords\":[\"aikido\",\"aikido en inca\",\"aikido en mallorca\",\"aikido inca\",\"aikido mallorca\",\"aikido palma\",\"aikido sineu\",\"aikikai\",\"incaciutat\",\"mallorca\",\"mallorca aikikai\",\"spain aikikai\"],\"articleSection\":[\"AIKIDO\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca\",\"url\":\"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca\",\"name\":\"Aikido. Guillermo Balderas Sensei. Enero 2025. Seishin Aikido Mallorca. - SEISHIN AIKIDO MALLORCA\",\"isPartOf\":{\"@id\":\"https:\/\/seishinaikidomallorca.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca#primaryimage\"},\"image\":{\"@id\":\"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca#primaryimage\"},\"thumbnailUrl\":\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/12\/467640769_1117305276881021_5944476159786189480_n.jpg\",\"datePublished\":\"2024-12-05T10:25:01+00:00\",\"dateModified\":\"2024-12-05T10:32:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca#primaryimage\",\"url\":\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/12\/467640769_1117305276881021_5944476159786189480_n.jpg\",\"contentUrl\":\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/12\/467640769_1117305276881021_5944476159786189480_n.jpg\",\"width\":1440,\"height\":1440,\"caption\":\"Seishin Aikido Mallorca. Guillermo Balderas Sensei.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/seishinaikidomallorca.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aikido. Guillermo Balderas Sensei. Enero 2025. Seishin Aikido Mallorca.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/seishinaikidomallorca.com\/#website\",\"url\":\"https:\/\/seishinaikidomallorca.com\/\",\"name\":\"SEISHIN AIKIDO MALLORCA\",\"description\":\"AIKIDO EN MALLORCA | AIKIDO EN PALMA Y SINEU\",\"publisher\":{\"@id\":\"https:\/\/seishinaikidomallorca.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/seishinaikidomallorca.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/seishinaikidomallorca.com\/#organization\",\"name\":\"SEISHIN AIKIDO MALLORCA\",\"url\":\"https:\/\/seishinaikidomallorca.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/seishinaikidomallorca.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/03\/mon-scaled.jpg\",\"contentUrl\":\"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/03\/mon-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"SEISHIN AIKIDO MALLORCA\"},\"image\":{\"@id\":\"https:\/\/seishinaikidomallorca.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/seishinaikidomallorca\",\"https:\/\/www.instagram.com\/seishinaikidomallorca\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/seishinaikidomallorca.com\/#\/schema\/person\/b710dec9276d5d3ecacea9edc5d4cddc\",\"name\":\"llorenc\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/seishinaikidomallorca.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/seishinaikidomallorca.com\/wp-content\/litespeed\/avatar\/212b229553e7d372d38e2f6001354d19.jpg?ver=1778636132\",\"contentUrl\":\"https:\/\/seishinaikidomallorca.com\/wp-content\/litespeed\/avatar\/212b229553e7d372d38e2f6001354d19.jpg?ver=1778636132\",\"caption\":\"llorenc\"},\"description\":\"Maestro de Aikido. Director de la escuela Seishin Aikido Mallorca.\",\"sameAs\":[\"https:\/\/seishinaikidomallorca.com\/sensei\"],\"url\":\"https:\/\/seishinaikidomallorca.com\/en\/author\/llorenc\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aikido. Guillermo Balderas Sensei. Enero 2025. Seishin Aikido Mallorca. - SEISHIN AIKIDO MALLORCA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seishinaikidomallorca.com\/en\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca\/","og_locale":"en_GB","og_type":"article","og_title":"Aikido. Guillermo Balderas Sensei. Enero 2025. Seishin Aikido Mallorca. - SEISHIN AIKIDO MALLORCA","og_description":"Seminario de Aikido en Mallorca. Guillermo Balderas Sensei. Seishin Dojo C\/Regal, 114. D\u00edas 10 y 11 de enero de 2025. Seminario de Aikido reconocido por Spain Aikikai y por la&hellip;&nbsp;Read More &raquo;Aikido. Guillermo Balderas Sensei. Enero 2025. Seishin Aikido Mallorca.","og_url":"https:\/\/seishinaikidomallorca.com\/en\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca\/","og_site_name":"SEISHIN AIKIDO MALLORCA","article_publisher":"https:\/\/www.facebook.com\/seishinaikidomallorca","article_published_time":"2024-12-05T10:25:01+00:00","article_modified_time":"2024-12-05T10:32:06+00:00","og_image":[{"width":1440,"height":1440,"url":"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/12\/467640769_1117305276881021_5944476159786189480_n.jpg","type":"image\/jpeg"}],"author":"llorenc","twitter_card":"summary_large_image","twitter_misc":{"Written by":"llorenc","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca#article","isPartOf":{"@id":"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca"},"author":{"name":"llorenc","@id":"https:\/\/seishinaikidomallorca.com\/#\/schema\/person\/b710dec9276d5d3ecacea9edc5d4cddc"},"headline":"Aikido. Guillermo Balderas Sensei. Enero 2025. Seishin Aikido Mallorca.","datePublished":"2024-12-05T10:25:01+00:00","dateModified":"2024-12-05T10:32:06+00:00","mainEntityOfPage":{"@id":"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca"},"wordCount":80,"commentCount":0,"publisher":{"@id":"https:\/\/seishinaikidomallorca.com\/#organization"},"image":{"@id":"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca#primaryimage"},"thumbnailUrl":"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/12\/467640769_1117305276881021_5944476159786189480_n.jpg","keywords":["aikido","aikido en inca","aikido en mallorca","aikido inca","aikido mallorca","aikido palma","aikido sineu","aikikai","incaciutat","mallorca","mallorca aikikai","spain aikikai"],"articleSection":["AIKIDO"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca#respond"]}]},{"@type":"WebPage","@id":"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca","url":"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca","name":"Aikido. Guillermo Balderas Sensei. Enero 2025. Seishin Aikido Mallorca. - SEISHIN AIKIDO MALLORCA","isPartOf":{"@id":"https:\/\/seishinaikidomallorca.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca#primaryimage"},"image":{"@id":"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca#primaryimage"},"thumbnailUrl":"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/12\/467640769_1117305276881021_5944476159786189480_n.jpg","datePublished":"2024-12-05T10:25:01+00:00","dateModified":"2024-12-05T10:32:06+00:00","breadcrumb":{"@id":"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca#primaryimage","url":"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/12\/467640769_1117305276881021_5944476159786189480_n.jpg","contentUrl":"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/12\/467640769_1117305276881021_5944476159786189480_n.jpg","width":1440,"height":1440,"caption":"Seishin Aikido Mallorca. Guillermo Balderas Sensei."},{"@type":"BreadcrumbList","@id":"https:\/\/seishinaikidomallorca.com\/aikido-guillermo-balderas-sensei-enero-2025-seishin-aikido-mallorca#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/seishinaikidomallorca.com\/"},{"@type":"ListItem","position":2,"name":"Aikido. Guillermo Balderas Sensei. Enero 2025. Seishin Aikido Mallorca."}]},{"@type":"WebSite","@id":"https:\/\/seishinaikidomallorca.com\/#website","url":"https:\/\/seishinaikidomallorca.com\/","name":"SEISHIN AIKIDO MALLORCA","description":"AIKIDO EN MALLORCA | AIKIDO EN PALMA Y SINEU","publisher":{"@id":"https:\/\/seishinaikidomallorca.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seishinaikidomallorca.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/seishinaikidomallorca.com\/#organization","name":"SEISHIN AIKIDO MALLORCA","url":"https:\/\/seishinaikidomallorca.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/seishinaikidomallorca.com\/#\/schema\/logo\/image\/","url":"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/03\/mon-scaled.jpg","contentUrl":"https:\/\/seishinaikidomallorca.com\/wp-content\/uploads\/2024\/03\/mon-scaled.jpg","width":2560,"height":2560,"caption":"SEISHIN AIKIDO MALLORCA"},"image":{"@id":"https:\/\/seishinaikidomallorca.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/seishinaikidomallorca","https:\/\/www.instagram.com\/seishinaikidomallorca"]},{"@type":"Person","@id":"https:\/\/seishinaikidomallorca.com\/#\/schema\/person\/b710dec9276d5d3ecacea9edc5d4cddc","name":"llorenc","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/seishinaikidomallorca.com\/#\/schema\/person\/image\/","url":"https:\/\/seishinaikidomallorca.com\/wp-content\/litespeed\/avatar\/212b229553e7d372d38e2f6001354d19.jpg?ver=1778636132","contentUrl":"https:\/\/seishinaikidomallorca.com\/wp-content\/litespeed\/avatar\/212b229553e7d372d38e2f6001354d19.jpg?ver=1778636132","caption":"llorenc"},"description":"Maestro de Aikido. Director de la escuela Seishin Aikido Mallorca.","sameAs":["https:\/\/seishinaikidomallorca.com\/sensei"],"url":"https:\/\/seishinaikidomallorca.com\/en\/author\/llorenc"}]}},"_links":{"self":[{"href":"https:\/\/seishinaikidomallorca.com\/en\/wp-json\/wp\/v2\/posts\/1149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seishinaikidomallorca.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seishinaikidomallorca.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seishinaikidomallorca.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/seishinaikidomallorca.com\/en\/wp-json\/wp\/v2\/comments?post=1149"}],"version-history":[{"count":1,"href":"https:\/\/seishinaikidomallorca.com\/en\/wp-json\/wp\/v2\/posts\/1149\/revisions"}],"predecessor-version":[{"id":1150,"href":"https:\/\/seishinaikidomallorca.com\/en\/wp-json\/wp\/v2\/posts\/1149\/revisions\/1150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seishinaikidomallorca.com\/en\/wp-json\/wp\/v2\/media\/1146"}],"wp:attachment":[{"href":"https:\/\/seishinaikidomallorca.com\/en\/wp-json\/wp\/v2\/media?parent=1149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seishinaikidomallorca.com\/en\/wp-json\/wp\/v2\/categories?post=1149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seishinaikidomallorca.com\/en\/wp-json\/wp\/v2\/tags?post=1149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}